{"id":7,"count":18,"description":"","link":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/category\/research-themes\/eppbl\/","name":"Lifelong learners in diverse contexts: workplace, professional, and community learning","slug":"eppbl","taxonomy":"category","parent":10,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/testblogs.griffith.edu.au\/gierinsights\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}